{"id":153,"count":1,"description":"","link":"https:\/\/mehmehs.com\/aliyah\/tag\/jpost\/","name":"jpost","slug":"jpost","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>jpost Archives - Diary of an Aliyah-nik<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mehmehs.com\/aliyah\/tag\/jpost\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"jpost Archives - Diary of an Aliyah-nik\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mehmehs.com\/aliyah\/tag\/jpost\/\" \/>\n<meta property=\"og:site_name\" content=\"Diary of an Aliyah-nik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/mehmehs.com\\\/aliyah\\\/tag\\\/jpost\\\/\",\"url\":\"https:\\\/\\\/mehmehs.com\\\/aliyah\\\/tag\\\/jpost\\\/\",\"name\":\"jpost Archives - Diary of an Aliyah-nik\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mehmehs.com\\\/aliyah\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mehmehs.com\\\/aliyah\\\/tag\\\/jpost\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mehmehs.com\\\/aliyah\\\/tag\\\/jpost\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mehmehs.com\\\/aliyah\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"jpost\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mehmehs.com\\\/aliyah\\\/#website\",\"url\":\"https:\\\/\\\/mehmehs.com\\\/aliyah\\\/\",\"name\":\"Diary of an Aliyah-nik\",\"description\":\"A family&#039;s aliyah journey from North of London to the Galilee in Northern Israel\",\"publisher\":{\"@id\":\"https:\\\/\\\/mehmehs.com\\\/aliyah\\\/#\\\/schema\\\/person\\\/69d3555c26668f912c5575ce56829b4c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mehmehs.com\\\/aliyah\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/mehmehs.com\\\/aliyah\\\/#\\\/schema\\\/person\\\/69d3555c26668f912c5575ce56829b4c\",\"name\":\"Deganit\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/920ba5e82b8ea5ade00e9edb3c8196e925b055201c954dcd9d5b9e36a613e441?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/920ba5e82b8ea5ade00e9edb3c8196e925b055201c954dcd9d5b9e36a613e441?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/920ba5e82b8ea5ade00e9edb3c8196e925b055201c954dcd9d5b9e36a613e441?s=96&d=mm&r=g\",\"caption\":\"Deganit\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/920ba5e82b8ea5ade00e9edb3c8196e925b055201c954dcd9d5b9e36a613e441?s=96&d=mm&r=g\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"jpost Archives - Diary of an Aliyah-nik","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mehmehs.com\/aliyah\/tag\/jpost\/","og_locale":"en_GB","og_type":"article","og_title":"jpost Archives - Diary of an Aliyah-nik","og_url":"https:\/\/mehmehs.com\/aliyah\/tag\/jpost\/","og_site_name":"Diary of an Aliyah-nik","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/mehmehs.com\/aliyah\/tag\/jpost\/","url":"https:\/\/mehmehs.com\/aliyah\/tag\/jpost\/","name":"jpost Archives - Diary of an Aliyah-nik","isPartOf":{"@id":"https:\/\/mehmehs.com\/aliyah\/#website"},"breadcrumb":{"@id":"https:\/\/mehmehs.com\/aliyah\/tag\/jpost\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/mehmehs.com\/aliyah\/tag\/jpost\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mehmehs.com\/aliyah\/"},{"@type":"ListItem","position":2,"name":"jpost"}]},{"@type":"WebSite","@id":"https:\/\/mehmehs.com\/aliyah\/#website","url":"https:\/\/mehmehs.com\/aliyah\/","name":"Diary of an Aliyah-nik","description":"A family&#039;s aliyah journey from North of London to the Galilee in Northern Israel","publisher":{"@id":"https:\/\/mehmehs.com\/aliyah\/#\/schema\/person\/69d3555c26668f912c5575ce56829b4c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mehmehs.com\/aliyah\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":["Person","Organization"],"@id":"https:\/\/mehmehs.com\/aliyah\/#\/schema\/person\/69d3555c26668f912c5575ce56829b4c","name":"Deganit","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/920ba5e82b8ea5ade00e9edb3c8196e925b055201c954dcd9d5b9e36a613e441?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/920ba5e82b8ea5ade00e9edb3c8196e925b055201c954dcd9d5b9e36a613e441?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/920ba5e82b8ea5ade00e9edb3c8196e925b055201c954dcd9d5b9e36a613e441?s=96&d=mm&r=g","caption":"Deganit"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/920ba5e82b8ea5ade00e9edb3c8196e925b055201c954dcd9d5b9e36a613e441?s=96&d=mm&r=g"}}]}},"_links":{"self":[{"href":"https:\/\/mehmehs.com\/aliyah\/wp-json\/wp\/v2\/tags\/153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mehmehs.com\/aliyah\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/mehmehs.com\/aliyah\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/mehmehs.com\/aliyah\/wp-json\/wp\/v2\/posts?tags=153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}